{"id":75223,"date":"2024-12-06T19:11:50","date_gmt":"2024-12-06T19:11:50","guid":{"rendered":"https:\/\/notioeste.com\/?p=75223"},"modified":"2024-12-06T19:11:51","modified_gmt":"2024-12-06T19:11:51","slug":"cuales-son-los-remedios-que-pasan-a-venta-libre","status":"publish","type":"post","link":"https:\/\/notioeste.com\/index.php\/2024\/12\/06\/cuales-son-los-remedios-que-pasan-a-venta-libre\/","title":{"rendered":"\u00bfCU\u00c1LES SON LOS REMEDIOS QUE PASAN A VENTA LIBRE ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La ANMAT descarta la necesidad de receta en dosis\u00a0 bajas del compuesto acetilcist\u00e9nia por falta de efectos adversos graves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principio de este a\u00f1o, a trav\u00e9s de la resoluci\u00f3n 284, el Gobierno le encomend\u00f3 a la ANMAT que revise cuales medicamentos podr\u00edan cambiar su condici\u00f3n de venta bajo receta a venta libre. Estos quedaran sin el descuesto del 40% sobre el precio en mostrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esta raz\u00f3n, la ANMAT dicto que los medicamentos por una cantidad de hasta 400mg del compuesto <strong>acetilciste\u00edna<\/strong>, encontrados con mayor frecuencia en descongestivos de las v\u00edas respiratorias superiores. A la venta libre pasaran todas las formulaciones de 200mg, como las del vadem\u00e9cum, las de 600mg seguir\u00e1 regida por receta y con descuento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale aclarar, que actualmente, no se existen medicamentos en el mercado que cumplan con estas condiciones, por lo que el ANMAt segura que la medida se genera por si en el futuro podr\u00eda haber&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las presentaciones m\u00e1s frecuentes de acetilciste\u00edna de 200 mg son utilizadas para pediatr\u00eda. Aunque, la disposici\u00f3n de la ANMAT, publicada este viernes en el Bolet\u00edn Oficial, apunta la mediada a \u201cadultos y mayores de 14 a\u00f1os\u201d y aconseja no cambiar las indicaciones para los mejores de 14 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace unos d\u00edas, el Gobierno public\u00f3 un decreto en donde se habilita la exhibici\u00f3n de los miramientos de venta sin receta en las g\u00f3ndolas de las farmacias, al alcance del p\u00fablico sin necesidad de la atenci\u00f3n de un farmac\u00e9utico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ANMAT descarta la necesidad de receta en dosis\u00a0 bajas del compuesto acetilcist\u00e9nia por falta de efectos adversos graves. A principio de este a\u00f1o, a trav\u00e9s de la resoluci\u00f3n 284, el Gobierno le encomend\u00f3 a la ANMAT que revise cuales medicamentos podr\u00edan cambiar su condici\u00f3n de venta bajo receta a venta libre. Estos quedaran sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[29,226],"tags":[],"class_list":["post-75223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional-superior","category-salud-naciona"],"_links":{"self":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/75223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=75223"}],"version-history":[{"count":1,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/75223\/revisions"}],"predecessor-version":[{"id":75226,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/75223\/revisions\/75226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/media\/75225"}],"wp:attachment":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=75223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=75223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=75223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}