{"id":73070,"date":"2024-01-31T20:14:45","date_gmt":"2024-01-31T20:14:45","guid":{"rendered":"https:\/\/notioeste.com\/?p=73070"},"modified":"2024-01-31T20:14:47","modified_gmt":"2024-01-31T20:14:47","slug":"cuota-simple-el-plan-de-financiamiento-que-regira-a-partir-de-febrero","status":"publish","type":"post","link":"https:\/\/notioeste.com\/index.php\/2024\/01\/31\/cuota-simple-el-plan-de-financiamiento-que-regira-a-partir-de-febrero\/","title":{"rendered":"&#8220;CUOTA SIMPLE&#8221;: EL PLAN DE FINANCIAMIENTO QUE REGIR\u00c1 A PARTIR DE FEBRERO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Gobierno nacional pondr\u00e1 en marcha el programa Cuota Simple, que sustituye el Ahora 12, a partir de este jueves y funcionar\u00e1 hasta el pr\u00f3ximo 31 de mayo con el objetivo de brindarle a los compradores la posibilidad de financiar compras en tres y seis cuotas con tarjetas de cr\u00e9dito bancarias \u201ccon la tasa m\u00e1s baja del mercado\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el Palacio de Hacienda subrayaron que \u201cel financiamiento en cuotas es una herramienta muy valorada por los consumidores y comerciantes porque, adem\u00e1s de impulsar el consumo, representa un gran incentivo para la industria nacional y la generaci\u00f3n de empleo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuota Simple est\u00e1 compuesto por 30 categor\u00edas de productos de fabricaci\u00f3n nacional e internacional como: indumentaria, calzado y marroquiner\u00eda; la l\u00ednea blanca; tel\u00e9fonos celulares; muebles, servicios educativos; colchones; neum\u00e1ticos, accesorios, kit de conversi\u00f3n de veh\u00edculos a gas GNC y repuestos para automotores y motos; y televisores y monitores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, seg\u00fan infiormaron desde el Minister\u00edo de Econom\u00eda y la Secretar\u00eda de Comercio el programa tendr\u00e1 un alcance&nbsp;&nbsp;<strong>a nivel nacional y estar\u00e1 disponible todos los d\u00edas de la semana<\/strong>&nbsp;en los locales adheridos tanto de forma virtual o f\u00edsica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la tasa de Cuota Simple la<strong>\u00a0tasa ser\u00e1 del 93,5 por ciento con respecto de la Tasa Nominal Anual (TNA) del Banco Central (BCRA) que actualmente es del 110 por ciento. El Gobierno financiar\u00e1 un peque\u00f1o porcentaje para que los usuarios adquieran productos y alimentos de forma m\u00e1s accesible.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n te puede interesar: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/notioeste.com\/index.php\/2024\/01\/30\/merlo-celebra-talleres-gratuitos-para-el-verano\/\">MERLO CELEBRA TALLERES GRATUITOS PARA EL VERANO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno nacional pondr\u00e1 en marcha el programa Cuota Simple, que sustituye el Ahora 12, a partir de este jueves y funcionar\u00e1 hasta el pr\u00f3ximo 31 de mayo con el objetivo de brindarle a los compradores la posibilidad de financiar compras en tres y seis cuotas con tarjetas de cr\u00e9dito bancarias \u201ccon la tasa m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-73070","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/73070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=73070"}],"version-history":[{"count":1,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/73070\/revisions"}],"predecessor-version":[{"id":73072,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/posts\/73070\/revisions\/73072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/media\/73071"}],"wp:attachment":[{"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=73070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=73070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notioeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=73070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}